{"id":5734,"date":"2021-09-22T11:19:15","date_gmt":"2021-09-22T09:19:15","guid":{"rendered":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/"},"modified":"2026-07-05T15:29:27","modified_gmt":"2026-07-05T13:29:27","slug":"weingut-burggarten-blanc-de-noir","status":"publish","type":"product","link":"https:\/\/wijnclubamsterdam.nl\/en\/product\/weingut-burggarten-blanc-de-noir\/","title":{"rendered":"Weingut Burggarten Blanc de Noir"},"content":{"rendered":"<h2>Denk niet wit, denk niet zwart, denk niet zwart-wit, maar in de kleur van je wijn !<\/h2>\n<p>Het is ook verwarrend,<span style=\"color: #ff0000\">\u00a0<\/span>een wijn die ze Blanc de Noir noemen. Maar het betekent gewoon &#8220;witte wijn van blauwe druiven&#8221;. In dit geval gemaakt van de<a href=\"https:\/\/wijnclubamsterdam.nl\/en\/druiven\/pinot-noir\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0Sp\u00e4tburgunder<\/a> druif door deze direct te persen zonder de schillen en<span style=\"color: #ff0000\">\u00a0<\/span>te laten inweken (macereren met een mooi woord. Een goede Blanc de Noir is heel licht van kleur en fris van<span style=\"color: #ff0000\">\u00a0<\/span>smaak, aldus Paul Sch\u00e4fer van Weingut Burggarten uuit de Ahr. Overigens is dit het &#8220;Weingut des Jahres 2020&#8221; in de Ahr.\u00a0 Paul kiest in de Weingut Burggarten Blanc de Noir voor\u00a0 geen schil-weking om zoveel mogelijk het frisse karakter van de wijn te laten spreken. Hier dus geen oranje\/ros\u00e9 zweem in het glas maar een mooie heldere groengele kleur. In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur. Een verleidelijke, zachte en zeer drinkbare Blanc de Noir hebben we\u00a0 hier dus! De Weingut Burggarten Blanc de Noir is heerlijk om als aperitief te drinken. Ook heerlijk bij frisse salades zoals een krab salade met pomelo en gaat ook heel fijn samen met bijvoorbeeld de Vietnamese keuken.<\/p>\n<h3>Weingut des Jahres 2020: dus kwaliteit voor alles<\/h3>\n<p>Weingut Burggarten staat voor wijnen waar ze zelf van genieten. Om dit te doen, verlagen ze de opbrengsten en verlengen ze<span style=\"color: #ff0000\">\u00a0<\/span>de rijpingstijden. Deze harmonieuze samenwerking resulteert in wijnen van de hoogste kwaliteit, voor wie<span style=\"color: #ff0000\">\u00a0<\/span><span style=\"color: #000000\">o<\/span>ok de belangrijkste critici hun waardering uitspreken. Ondanks de zeer noordelijke ligging van de Ahr, (50-51 graden noorderbreedte) is dit gebied beroemd vanwege zijn elegante rode wijnen. Sp\u00e4tburgunder en Fr\u00fchburgunder zijn de twee belangrijkste druiven voor de Ahr. Waar de Sp\u00e4tburgunder internationaal bekendheid geniet onder zijn synoniem Pinot Noir, is Fr\u00fchburgunder (ook wel de Pinot Madeleine genoemd)\u00a0 een meer onbekend druivenras voor velen. Fr\u00fchburgunder is een mutatie van de Sp\u00e4tburgunder en heeft dus overeenkomende karakteristieken. De naam heeft deze druif te danken aan het feit dat hij over het algemeen twee weken eerder rijp is dan de Sp\u00e4tburgunder. In de Ahr bestaat de bodem voornamelijk uit leisteen, grauwacke en vulkanisch gesteente. Weingut Burggarten bezit wijngaarden in al deze categorie\u00ebn en laat<span style=\"color: #ff0000\">\u00a0<\/span>daarmee de prachtige diversiteit van de Ahr vallei zien. Weingut Burggarten produceert 120.000 flessen per jaar afkomstig van 14 hectare.<\/p>","protected":false},"excerpt":{"rendered":"<p>Denk niet wit, denk niet zwart, denk niet zwart-wit, maar in de kleur van je wijn ! Het is ook verwarrend,\u00a0een wijn die ze Blanc de Noir noemen. Maar het betekent gewoon &#8220;witte wijn van blauwe druiven&#8221;. In dit geval gemaakt van de\u00a0Sp\u00e4tburgunder druif door deze direct te persen zonder de schillen en\u00a0te laten inweken [&hellip;]<\/p>\n","protected":false},"featured_media":5733,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_joinchat":[]},"product_brand":[],"product_cat":[29],"product_tag":[2313],"pa_smaakprofiel":[],"class_list":{"0":"post-5734","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-witte-wijn","7":"product_tag-duitse-witte-wijn","8":"pa_alcohol-12-procent","9":"pa_classificatie-qba","10":"pa_domein-weingut-burggarten","11":"pa_druif-spatburgunder","12":"pa_inhoud-0-75-liter","13":"pa_jaar-2856","14":"pa_regio-ahr","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Weingut Burggarten Blanc de Noir - WijnclubAmsterdam.nl<\/title>\n<meta name=\"description\" content=\"Weingut Burggarten Blanc de Noir heeft In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wijnclubamsterdam.nl\/en\/product\/weingut-burggarten-blanc-de-noir\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weingut Burggarten Blanc de Noir\" \/>\n<meta property=\"og:description\" content=\"Weingut Burggarten Blanc de Noir heeft In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wijnclubamsterdam.nl\/en\/product\/weingut-burggarten-blanc-de-noir\/\" \/>\n<meta property=\"og:site_name\" content=\"WijnclubAmsterdam.nl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wijnclubamsterdam.nl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-05T13:29:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2021\/09\/Blanc-de-Noir-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"1140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/\",\"url\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/\",\"name\":\"Weingut Burggarten Blanc de Noir - WijnclubAmsterdam.nl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2021\\\/09\\\/Blanc-de-Noir-4.png\",\"datePublished\":\"2021-09-22T09:19:15+00:00\",\"dateModified\":\"2026-07-05T13:29:27+00:00\",\"description\":\"Weingut Burggarten Blanc de Noir heeft In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2021\\\/09\\\/Blanc-de-Noir-4.png\",\"contentUrl\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2021\\\/09\\\/Blanc-de-Noir-4.png\",\"width\":400,\"height\":1140,\"caption\":\"Blanc-de-Noir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/product\\\/weingut-burggarten-blanc-de-noir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blanc de Noir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/#website\",\"url\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/\",\"name\":\"WijnclubAmsterdam.nl\",\"description\":\"online wijnwinkel met groot assortiment wijnen\",\"publisher\":{\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/#organization\",\"name\":\"Wijnclubasmterdam.nl\",\"url\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2020\\\/01\\\/wijnclub_logo_vierkant.png\",\"contentUrl\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/wp-content\\\/uploads\\\/sites\\\/20\\\/2020\\\/01\\\/wijnclub_logo_vierkant.png\",\"width\":427,\"height\":427,\"caption\":\"Wijnclubasmterdam.nl\"},\"image\":{\"@id\":\"https:\\\/\\\/wijnclubamsterdam.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wijnclubamsterdam.nl\",\"https:\\\/\\\/www.instagram.com\\\/wijnclubamsterdam\\\/\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Weingut Burggarten Blanc de Noir - WijnclubAmsterdam.nl","description":"Weingut Burggarten Blanc de Noir heeft In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wijnclubamsterdam.nl\/en\/product\/weingut-burggarten-blanc-de-noir\/","og_locale":"en_US","og_type":"article","og_title":"Weingut Burggarten Blanc de Noir","og_description":"Weingut Burggarten Blanc de Noir heeft In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur.","og_url":"https:\/\/wijnclubamsterdam.nl\/en\/product\/weingut-burggarten-blanc-de-noir\/","og_site_name":"WijnclubAmsterdam.nl","article_publisher":"https:\/\/www.facebook.com\/wijnclubamsterdam.nl","article_modified_time":"2026-07-05T13:29:27+00:00","og_image":[{"width":400,"height":1140,"url":"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2021\/09\/Blanc-de-Noir-4.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/","url":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/","name":"Weingut Burggarten Blanc de Noir - WijnclubAmsterdam.nl","isPartOf":{"@id":"https:\/\/wijnclubamsterdam.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/#primaryimage"},"image":{"@id":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/#primaryimage"},"thumbnailUrl":"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2021\/09\/Blanc-de-Noir-4.png","datePublished":"2021-09-22T09:19:15+00:00","dateModified":"2026-07-05T13:29:27+00:00","description":"Weingut Burggarten Blanc de Noir heeft In de geur een limoen schilletje, granny smith appel en jasmijn. De smaak is heel fris, met een prachtige balans tussen zoet en zuur.","breadcrumb":{"@id":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/#primaryimage","url":"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2021\/09\/Blanc-de-Noir-4.png","contentUrl":"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2021\/09\/Blanc-de-Noir-4.png","width":400,"height":1140,"caption":"Blanc-de-Noir"},{"@type":"BreadcrumbList","@id":"https:\/\/wijnclubamsterdam.nl\/product\/weingut-burggarten-blanc-de-noir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wijnclubamsterdam.nl\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/wijnclubamsterdam.nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"Blanc de Noir"}]},{"@type":"WebSite","@id":"https:\/\/wijnclubamsterdam.nl\/#website","url":"https:\/\/wijnclubamsterdam.nl\/","name":"WijnclubAmsterdam.nl","description":"online wijnwinkel met groot assortiment wijnen","publisher":{"@id":"https:\/\/wijnclubamsterdam.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wijnclubamsterdam.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wijnclubamsterdam.nl\/#organization","name":"Wijnclubasmterdam.nl","url":"https:\/\/wijnclubamsterdam.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wijnclubamsterdam.nl\/#\/schema\/logo\/image\/","url":"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2020\/01\/wijnclub_logo_vierkant.png","contentUrl":"https:\/\/wijnclubamsterdam.nl\/wp-content\/uploads\/sites\/20\/2020\/01\/wijnclub_logo_vierkant.png","width":427,"height":427,"caption":"Wijnclubasmterdam.nl"},"image":{"@id":"https:\/\/wijnclubamsterdam.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wijnclubamsterdam.nl","https:\/\/www.instagram.com\/wijnclubamsterdam\/"]}]},"product_price_amount":"16.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"acf":{"punten":null,"top_10_beschrijving":null,"veelgestelde_vragen":null,"knop_tekst":null,"knop_url":null},"_links":{"self":[{"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/product\/5734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/comments?post=5734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/media\/5733"}],"wp:attachment":[{"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/media?parent=5734"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/product_brand?post=5734"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/product_cat?post=5734"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/product_tag?post=5734"},{"taxonomy":"pa_smaakprofiel","embeddable":true,"href":"https:\/\/wijnclubamsterdam.nl\/en\/wp-json\/wp\/v2\/pa_smaakprofiel?post=5734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}